{"id":5197,"date":"2025-06-18T12:48:59","date_gmt":"2025-06-18T17:48:59","guid":{"rendered":"https:\/\/iicbogota.esteri.it\/?page_id=5197"},"modified":"2026-05-12T11:21:09","modified_gmt":"2026-05-12T16:21:09","slug":"corsi-estivi","status":"publish","type":"page","link":"https:\/\/iicbogota.esteri.it\/it\/lingua-e-cultura\/i-corsi-di-lingua\/corsi-estivi\/","title":{"rendered":"Corsi estivi"},"content":{"rendered":"<p><em>(PROSSIMAMENTE).<\/em><\/p>\n<p>Dal 23 luglio al 25 agosto 2026 l&#8217;Istituto Italiano di Cultura amplia la sua <strong>offerta didattica con i corsi estivi<\/strong>: corso super-intensivo, laboratori di pratica e ripasso e laboratori di conversazione.<\/p>\n<p>Potrai iscriverti al <span style=\"color: #ff0000;\"><strong>corso superintensivo<\/strong> <\/span>a partire dal 1\u00b0 giugno.<br data-start=\"112\" data-end=\"115\" \/>Il corso ha una durata di 64 ore accademiche, con 3 ore di lezione al giorno dal luned\u00ec al venerd\u00ec.<br data-start=\"216\" data-end=\"219\" \/>La data di inizio del corso \u00e8 gioved\u00ec 23 luglio e le lezioni si concluderanno il 25 agosto 2026.<br \/>\nIl corso Super-Intensivo \u00e8 aperto a tutti i livelli di italiano (A1, A2, B1, B2 e C1) e ha un costo di <strong>1&#8217;250.000 COP<\/strong> e si sviluppa nei seguenti orari:<\/p>\n<ul>\n<li>8:00 &#8211; 11:00<\/li>\n<li>17:00 &#8211; 20:00<\/li>\n<\/ul>\n<p><strong>Prossimamente includeremo le informazioni per i corsi estivi.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Gli <strong>sconti<\/strong> stabiliti per l\u2019anno 2026 sono i seguenti:<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>Studenti attivi della Red de Centros Binacionales (IBRACO, Goethe Institut, British Council, Educaci\u00f2n Colombo-Japonesa, Colombo-Americano): 20% di sconto. Per maggiori informazioni entra nel sito della <strong><a href=\"https:\/\/www.redcentrosbinacionales.org\/convenios\/\">Red de Centros Binacionales<\/a><\/strong>;<\/li>\n<li>Studenti attivi delle Univesit\u00e0 Universidad Jorge Tadeo Lozano, Universidad Nacional de Colombia, Universidad de La Salle: 20% di sconto;<\/li>\n<li>Studenti attivi dell\u2019Universit\u00e0 Sergio Arboleda: 10% di sconto;<\/li>\n<li>Dipendenti Technip Group (Ex-TIPIEL): 20% di sconto;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"(PROSSIMAMENTE). Dal 23 luglio al 25 agosto 2026 l&#8217;Istituto Italiano di Cultura amplia la sua offerta didattica con i corsi estivi: corso super-intensivo, laboratori di pratica e ripasso e laboratori di conversazione. Potrai iscriverti al corso superintensivo a partire dal 1\u00b0 giugno.Il corso ha una durata di 64 ore accademiche, con 3 ore di lezione [&hellip;]","protected":false},"author":3,"featured_media":0,"parent":42,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5197","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/iicbogota.esteri.it\/it\/wp-json\/wp\/v2\/pages\/5197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iicbogota.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iicbogota.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iicbogota.esteri.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/iicbogota.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=5197"}],"version-history":[{"count":6,"href":"https:\/\/iicbogota.esteri.it\/it\/wp-json\/wp\/v2\/pages\/5197\/revisions"}],"predecessor-version":[{"id":6623,"href":"https:\/\/iicbogota.esteri.it\/it\/wp-json\/wp\/v2\/pages\/5197\/revisions\/6623"}],"up":[{"embeddable":true,"href":"https:\/\/iicbogota.esteri.it\/it\/wp-json\/wp\/v2\/pages\/42"}],"wp:attachment":[{"href":"https:\/\/iicbogota.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=5197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}